{"id":1318,"date":"2019-06-26T12:34:36","date_gmt":"2019-06-26T10:34:36","guid":{"rendered":"http:\/\/lisarose-moonpearl.com\/?post_type=project&#038;p=1318"},"modified":"2019-06-26T12:35:24","modified_gmt":"2019-06-26T10:35:24","slug":"1318","status":"publish","type":"project","link":"https:\/\/lisarose-moonpearl.com\/index.php\/project\/1318\/","title":{"rendered":"KOLINA, MON INTERFACE VERS L&rsquo;AUTRE MONDE"},"content":{"rendered":"\n<p><strong>(\u00e9crit en septembre 2018)<\/strong><\/p>\n\n\n\n<p>Au fur et \u00e0 mesure des ann\u00e9es, je r\u00e9alise le r\u00f4le primordial des chevaux, mais surtout de Kolina, dans ma vie et dans mon EVEIL spirituel.<\/p>\n\n\n\n<p>J&rsquo;ai d\u00e9j\u00e0 beaucoup \u00e9crit sur le sujet, je vais essayer de faire court et d&rsquo;apporter de nouveaux \u00e9l\u00e9ments \u00e0 ma r\u00e9flexion.<\/p>\n\n\n\n<p>Lundi 17 septembre 2018, je suis all\u00e9e voir Nadine. Elle r\u00e9\u00e9quilibre l&rsquo;\u00e9nergie et parvient \u00e0 se connecter \u00e0 l&rsquo;esprit de son patient et donc de ses guides. C&rsquo;est gr\u00e2ce \u00e0 eux qu&rsquo;elle per\u00e7oit les n\u0153uds et peut les d\u00e9nouer.<\/p>\n\n\n\n<p>Kolina&nbsp;? Elle m&rsquo;a oblig\u00e9 \u00e0 changer et m&rsquo;a ouvert les portes vers une autre dimension.<\/p>\n\n\n\n<p>Ce serait gr\u00e2ce \u00e0 Querida, ma ch\u00e8re disparue. Elle fait partie de mes guides. C&rsquo;est d&rsquo;ailleurs la premi\u00e8re fois que Nadine voit une guide animale ! Avec un chakra jaune intense et beaucoup de blanc.<\/p>\n\n\n\n<p>Beaucoup de choses me paraissent plus clair, du coup.<\/p>\n\n\n\n<p>De l\u00e0 o\u00f9 elle est, Querida me guide sur ma route spirituelle, \u00e0 travers les chevaux. Elle ne m&rsquo;en veut pas, elle veille sur moi. Je suis s\u00fbre que c&rsquo;est elle qui m&rsquo;a fait rencontrer Kolina, une autre jument, espagnole aussi, au caract\u00e8re de feu&nbsp;!<\/p>\n\n\n\n<p>Pourquoi Kolina \u00e9tait-elle si nerveuse, \u00e9motive, volcanique&nbsp;? Pour m&rsquo;apprendre \u00e0 me calmer. Ma volont\u00e9 de la contr\u00f4ler la stressait et son stress m&rsquo;envahissait \u00e0 mon tour. Depuis toujours, nous sommes \u00e9motionnellement li\u00e9es, miroirs l&rsquo;une de l&rsquo;autre.<\/p>\n\n\n\n<p>Avec elle, en appliquant les m\u00e9thodes \u00ab&nbsp;classiques&nbsp;\u00bb, j&rsquo;\u00e9tais face \u00e0 un mur. Nous communiquions tr\u00e8s mal l&rsquo;une avec l&rsquo;autre. Mais je ne l&rsquo;ai pas compris de suite&#8230;&nbsp;<\/p>\n\n\n\n<p>Il a fallu qu&rsquo;elle se fasse mal, qu&rsquo;elle soit arr\u00eat\u00e9e. Et que j&rsquo;aie peur de la perdre \u00e0 son tour\u00a0! Elle s&rsquo;est mise \u00e0 boiter du post\u00e9rieur droit, sans qu&rsquo;en r\u00e9alit\u00e9, il n&rsquo;y ait quoi que ce soit \u00e0 ce membre&#8230; Querida s&rsquo;\u00e9tait bless\u00e9e au post\u00e9rieur droit&#8230; C&rsquo;est pr\u00e9cis\u00e9ment cette blessure qui lui fut fatale.\u00a0<\/p>\n\n\n\n<p>Ironie du sort&nbsp;? Non. Juste un signe, on ne peut plus clair, de ma ch\u00e8re disparue. Du style&nbsp;: \u00ab&nbsp;Tu veux qu&rsquo;elle finisse comme moi&nbsp;??&nbsp;\u00bb<\/p>\n\n\n\n<p>J&rsquo;ai alors, \u00e0 l&rsquo;\u00e9poque, rencontr\u00e9 Manuela.&nbsp;<\/p>\n\n\n\n<p>Elle m&rsquo;a dit qu&rsquo;on voyait que j&rsquo;aimais ma jument, que je la travaillais avec mon c\u0153ur. Mais, d&rsquo;apr\u00e8s elle, je ne m&rsquo;y prenais pas de la bonne fa\u00e7on. Et m\u00eame, pire, j&rsquo;allais droit dans le mur. Elle a d\u00e9tect\u00e9 une pathologie interne aux ant\u00e9rieurs. Gr\u00e2ce \u00e0 elle, j&rsquo;ai fait des radios et ai su que mon colosse avait une \u00e9norme fragilit\u00e9 \u00e0 cet endroit, un colosse aux pieds d&rsquo;argile&#8230; Impossible d&rsquo;envisager une carri\u00e8re sportive pour Kolina.&nbsp;<\/p>\n\n\n\n<p>On m&rsquo;encouragea \u00e0 la vendre&#8230; Impossible. C&rsquo;\u00e9tait MA jument, mon enfant. M\u00eame plus\u00a0: mon alter ego. La jument dont j&rsquo;avait toujours r\u00eav\u00e9. Tant pis. Je ferais un trait sur mes ambitions \u00e9questres. Le tout c&rsquo;est que Kolina aille le mieux possible et que nous puissions faire une longue route ensemble. Querida \u00e9tait partie trop t\u00f4t. Je ne voulais pas qu&rsquo;il en soit de m\u00eame avec Kolina.<\/p>\n\n\n\n<p>J&rsquo;ai ensuite rencontr\u00e9 Tina, toujours par le plus grand des hasards.&nbsp;<\/p>\n\n\n\n<p>J&rsquo;\u00e9tais encore tent\u00e9e de poursuivre le dressage classique avec Kolina. Je r\u00eavais toujours, dans un coin de ma t\u00eate, de piaffer, de passage, de changement de pied au temps&#8230; Je ne savais pas par quels moyens y acc\u00e9der tout en respectant Kolina et surtout sa sant\u00e9&#8230;<\/p>\n\n\n\n<p>J&rsquo;ai mis des mois \u00e0 admettre que Tina m&rsquo;ouvrait les bonnes portes. J&rsquo;ai d\u00fb jeter tout ce que j&rsquo;avais appris avant. Des ann\u00e9es de travail, de bourrage de cr\u00e2ne, de mauvaises habitudes que je pensais bonnes&#8230; Bref&nbsp;: TABULA RASA.<\/p>\n\n\n\n<p>J&rsquo;ai \u00e9cout\u00e9 Tina, et ai pu constater \u00e0 quel point mon changement m\u00e9tamorphosait Kolina. Respirer par le ventre. Contr\u00f4ler l&rsquo;\u00e9nergie que je lui transmettais. Voil\u00e0 Kolina qui s&rsquo;est mise \u00e0 faire des arr\u00eats, r\u00eanes longues, et \u00e0 rester plus d&rsquo;une seconde \u00e0 l&rsquo;arr\u00eat, r\u00eanes d\u00e9tendues de surcro\u00eet. Le dragon l\u00e2chait sa rage, il commen\u00e7ait \u00e0 me faire confiance.<\/p>\n\n\n\n<p>J&rsquo;ai chang\u00e9 dans ma vie de tous les jours. J&rsquo;\u00e9tais plus calme, moins dans le contr\u00f4le de l&rsquo;autre (et de moi), plus \u00e0 l&rsquo;\u00e9coute. Moins dans la recherche de la performance, co\u00fbte que co\u00fbte. Les r\u00e9sultats \u00e9taient cependant aussi bons, voire meilleurs et parfois plus rapides que sous la contrainte. Comme quoi, le COEUR fonctionne toujours mieux que l&rsquo;EGO.<\/p>\n\n\n\n<p>Avec Duende, ensuite, que j&rsquo;ai connu depuis sa naissance, j&rsquo;ai agi tout autrement qu&rsquo;avec Kolina. Douceur, respect de son caract\u00e8re, de son rythme, de ses envies. Tout fut simple. J&rsquo;\u00e9tais uniquement dans le c\u0153ur et lui aussi. C&rsquo;\u00e9tait mon b\u00e9b\u00e9. Rien \u00e0 voir avec Kolina qui, \u00e9trangement, \u00e9tait devenue davantage une sorte de mentor&#8230;&nbsp;<\/p>\n\n\n\n<p>J&rsquo;ai appris encore mieux \u00e0 quel point l&rsquo;\u00e9nergie que je d\u00e9gageais avait une influence sur les chevaux. Pourtant, l&rsquo;\u00e9nergie, ce n&rsquo;est pas visible&#8230; Alors, j&rsquo;ai commenc\u00e9 \u00e0 croire \u00e0 l&rsquo;invisible, \u00e0 mettre de c\u00f4t\u00e9 mon c\u00f4t\u00e9 trop cart\u00e9sien et rationaliste. Je croyais sans voir car je le vivais.&nbsp;<\/p>\n\n\n\n<p>Je pensais alors aux personnes qui ont la foi et aux controverses qu&rsquo;elle ont avec les non croyants qui exigent des preuves&#8230; Les preuves, je les avais parce que je les \u00e9prouvais dans mon \u00eatre, dans mon c\u0153ur, dans mon quotidien. Mais personne de l&rsquo;ext\u00e9rieur ne les vivait \u00e0 ma place. De toute fa\u00e7on, je me fichais d\u00e9sormais du regard d&rsquo;autrui sur ma fa\u00e7on de faire avec les chevaux. Je m&rsquo;\u00e9coutais et les \u00e9coutais. POINT. Plus envie de briller en spectacle, en concours. Juste \u00eatre heureuse \u00e0 leurs c\u00f4t\u00e9s et que ce soit r\u00e9ciproque.&nbsp;<\/p>\n\n\n\n<p>Gr\u00e2ce \u00e0 Kolina, j&rsquo;ai \u00e9t\u00e9 confront\u00e9e aussi \u00e0 l&rsquo;exp\u00e9rimentation de la communication animale (CA). Je peux dire sans exag\u00e9ration que c&rsquo;est elle qui m&rsquo;a pouss\u00e9e encore plus loin dans ma qu\u00eate spirituelle&#8230;&nbsp;<\/p>\n\n\n\n<p>J&rsquo;ai connu Laure, qui m&rsquo;a permis d&rsquo;avance dans l&rsquo;invisible.&nbsp;<\/p>\n\n\n\n<p>J&rsquo;ai eu besoin de Laure pour parler \u00e0 Kolina, pour qu&rsquo;elle r\u00e9ponde \u00e0 mes questions.<\/p>\n\n\n\n<p>\u00ab&nbsp;Pourquoi boite-t-elle tous les trois jours quand je ne venais pas aux \u00e9curies&nbsp;?&nbsp;\u00bb<\/p>\n\n\n\n<p>\u00ab&nbsp;Pourquoi est-ce que je sens toujours ce stress en elle&nbsp;?&nbsp;\u00bb<\/p>\n\n\n\n<p>\u00ab&nbsp;Pourquoi est-ce toujours si compliqu\u00e9 avec elle. En comparaison avec Duende avec qui tout est simple, facile, joyeux&#8230;&nbsp;?&nbsp;\u00bb<\/p>\n\n\n\n<p>Je me suis rendue compte que de nombreuses personnes s&rsquo;int\u00e9ressaient \u00e0 ce type de communication inter-esp\u00e8ces. J&rsquo;ai m\u00eame adh\u00e9r\u00e9 \u00e0 un groupe FB qui lui est consacr\u00e9. De nombreuses personnes sont des communicantes animales. Elles ont ce don que j&rsquo;adorerais avoir et dont je r\u00eave depuis l&rsquo;enfance&nbsp;: \u00ab&nbsp;Parler aux animaux et recevoir des r\u00e9ponses de leur part.&nbsp;\u00bb<\/p>\n\n\n\n<p>Plus r\u00e9cemment encore, j&rsquo;ai compris que Kolina \u00e9tait mon double, vraiment. Je le pressentais. Nous vibrons toujours d&rsquo;une vibration identique, d&rsquo;une m\u00eame fr\u00e9quence. Mes \u00e9motions d\u00e9teignent sur elle et vis et versa. Gr\u00e2ce \u00e0 Loreena, j&rsquo;ai appris que nous \u00e9tions en r\u00e9alit\u00e9 comme un seul \u00eatre dans deux corps diff\u00e9rents. Nous avons la m\u00eame aura, rare, dor\u00e9e&#8230;<\/p>\n\n\n\n<p>Il faut que je sois sereine et heureuse pour que Kolina le soit aussi. Elle ressent tous mes stress et \u00e7a la fait somatiser.<\/p>\n\n\n\n<p>Ce que j&rsquo;avais \u00e9crit dans mon roman \u00ab\u00a0Alis\u00e9a\u00a0\u00bb, sur le fait que Cardona \u00e9tait l&rsquo;alter ego d&rsquo;Alis\u00e9a, se r\u00e9v\u00e8le \u00eatre un pressentiment qui montrait une r\u00e9alit\u00e9\u00a0: Kolina et moi sommes pareilles. Tout comme Querida et moi l&rsquo;\u00e9tions. Sauf qu&rsquo;avec Querida, la route n&rsquo;a pas \u00e9t\u00e9 aussi longue, assez longue, plut\u00f4t.<\/p>\n\n\n\n<p>J&rsquo;en reviens donc \u00e0 Querida et \u00e0 cette r\u00e9v\u00e9lation que j&rsquo;ai eu \u00e0 son sujet gr\u00e2ce \u00e0 Nadine. Querida est devenue mon guide, un de mes guides.<\/p>\n\n\n\n<p>Je ne sais pas si sa mort tragique faisait obligatoirement partie de mon chemin. Aurais-je chang\u00e9 ma vision et ma relation aux chevaux, et aurais-je tant chang\u00e9 moi-m\u00eame, si je ne l&rsquo;avais pas perdu de cette fa\u00e7on si brutale, injuste et douloureuse&#8230;&nbsp;? Impossible de le savoir.<\/p>\n\n\n\n<p>Ce qui est certain, c&rsquo;est que sa disparition fut le d\u00e9but de ma m\u00e9tamorphose. Tant de peine. Tellement de remises en questions&#8230; C&rsquo;est elle qui a mis Kolina sur ma route. Toutes les trois (ou quatre avec Cadix), nous sommes fait de la m\u00eame \u00e9toffe, c&rsquo;est clair.<\/p>\n\n\n\n<p>Kolina est donc bien, en quelque sorte, une autre Querida&#8230; M\u00eames chakras. M\u00eame aura.<\/p>\n\n\n\n<p>Mais comme au d\u00e9but, avec Kolina, je travaillais quasiment de la m\u00eame fa\u00e7on qu&rsquo;avec Querida, il me fallait de nouveaux \u00e9lectrochocs pour que je finisse vraiment par l\u00e2cher, \u00e9voluer.<\/p>\n\n\n\n<p>Kolina s&rsquo;est mise \u00e0 boiter. C&rsquo;\u00e9tait voulu, pour m&rsquo;interroger, me pousser dans mes retranchements. Me rappeler Querida. Puis j&rsquo;ai rencontr\u00e9 Manuela&#8230;, Tina&#8230; etc<\/p>\n\n\n\n<p>Et depuis, je ne fais que progresser sur ma route \u00e9quine (que je ne qualifierai m\u00eame plus d&rsquo;\u00e9questre).<\/p>\n\n\n\n<p>De l\u00e0 haut, et \u00e0 mes c\u00f4t\u00e9s au quotidien, Querida m&rsquo;aide \u00e0 avoir la bonne attitude, \u00e0 me poser les bonnes questions, \u00e0 m&rsquo;entourer des bonnes personnes, \u00e0 faire exactement ce qu&rsquo;il faut pour avoir une relation harmonieuse avec mes chevaux et que nous soyons tous heureux.<\/p>\n\n\n\n<p>Duende est l\u00e0 pour incarner la r\u00e9ussite de ma m\u00e9tamorphose. Il est la preuve que j&rsquo;ai compris, que mon changement a port\u00e9 ses fruits.<\/p>\n\n\n\n<p>D&rsquo;ailleurs, ce n&rsquo;est pas pour rien que c&rsquo;est lui que je destine \u00e0 Angelo. Il est le cheval id\u00e9al pour donner confiance \u00e0 un enfant et pour inculquer l&rsquo;amour des chevaux \u00e0 mon fils. Il est la continuit\u00e9 de mes liens aux chevaux.<\/p>\n\n\n\n<p>Querida =&gt; Kolina =&gt; Duende&nbsp;<\/p>\n\n\n\n<p>=&gt; =&gt; Lisa =&gt; =&gt; Angelo<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(\u00e9crit en septembre 2018) Au fur et \u00e0 mesure des ann\u00e9es, je r\u00e9alise le r\u00f4le primordial des chevaux, mais surtout de Kolina, dans ma vie et dans mon EVEIL spirituel. J&rsquo;ai d\u00e9j\u00e0 beaucoup \u00e9crit sur le sujet, je vais essayer de faire court et d&rsquo;apporter de nouveaux \u00e9l\u00e9ments \u00e0 ma r\u00e9flexion. Lundi 17 septembre 2018, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1319,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","_mi_skip_tracking":false,"footnotes":""},"project_category":[117],"project_tag":[],"_links":{"self":[{"href":"https:\/\/lisarose-moonpearl.com\/index.php\/wp-json\/wp\/v2\/project\/1318"}],"collection":[{"href":"https:\/\/lisarose-moonpearl.com\/index.php\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/lisarose-moonpearl.com\/index.php\/wp-json\/wp\/v2\/types\/project"}],"author":[{"embeddable":true,"href":"https:\/\/lisarose-moonpearl.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lisarose-moonpearl.com\/index.php\/wp-json\/wp\/v2\/comments?post=1318"}],"version-history":[{"count":3,"href":"https:\/\/lisarose-moonpearl.com\/index.php\/wp-json\/wp\/v2\/project\/1318\/revisions"}],"predecessor-version":[{"id":1322,"href":"https:\/\/lisarose-moonpearl.com\/index.php\/wp-json\/wp\/v2\/project\/1318\/revisions\/1322"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lisarose-moonpearl.com\/index.php\/wp-json\/wp\/v2\/media\/1319"}],"wp:attachment":[{"href":"https:\/\/lisarose-moonpearl.com\/index.php\/wp-json\/wp\/v2\/media?parent=1318"}],"wp:term":[{"taxonomy":"project_category","embeddable":true,"href":"https:\/\/lisarose-moonpearl.com\/index.php\/wp-json\/wp\/v2\/project_category?post=1318"},{"taxonomy":"project_tag","embeddable":true,"href":"https:\/\/lisarose-moonpearl.com\/index.php\/wp-json\/wp\/v2\/project_tag?post=1318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}